{"id":5858,"date":"2022-10-17T05:45:43","date_gmt":"2022-10-17T09:45:43","guid":{"rendered":"https:\/\/www.ftsgps.com\/?page_id=5858"},"modified":"2023-09-20T10:02:58","modified_gmt":"2023-09-20T14:02:58","slug":"atencion-al-cliente","status":"publish","type":"page","link":"https:\/\/www.ftsgps.com\/es\/customer-support\/","title":{"rendered":"Atenci\u00f3n al cliente"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\" style=\"font-size:40px\">Support Request<\/h2>\n\n\n<script type=\"text\/javascript\">\n\/* <![CDATA[ *\/\nvar gform;gform||(document.addEventListener(\"gform_main_scripts_loaded\",function(){gform.scriptsLoaded=!0}),document.addEventListener(\"gform\/theme\/scripts_loaded\",function(){gform.themeScriptsLoaded=!0}),window.addEventListener(\"DOMContentLoaded\",function(){gform.domLoaded=!0}),gform={domLoaded:!1,scriptsLoaded:!1,themeScriptsLoaded:!1,isFormEditor:()=>\"function\"==typeof InitializeEditor,callIfLoaded:function(o){return!(!gform.domLoaded||!gform.scriptsLoaded||!gform.themeScriptsLoaded&&!gform.isFormEditor()||(gform.isFormEditor()&&console.warn(\"The use of gform.initializeOnLoaded() is deprecated in the form editor context and will be removed in Gravity Forms 3.1.\"),o(),0))},initializeOnLoaded:function(o){gform.callIfLoaded(o)||(document.addEventListener(\"gform_main_scripts_loaded\",()=>{gform.scriptsLoaded=!0,gform.callIfLoaded(o)}),document.addEventListener(\"gform\/theme\/scripts_loaded\",()=>{gform.themeScriptsLoaded=!0,gform.callIfLoaded(o)}),window.addEventListener(\"DOMContentLoaded\",()=>{gform.domLoaded=!0,gform.callIfLoaded(o)}))},hooks:{action:{},filter:{}},addAction:function(o,r,e,t){gform.addHook(\"action\",o,r,e,t)},addFilter:function(o,r,e,t){gform.addHook(\"filter\",o,r,e,t)},doAction:function(o){gform.doHook(\"action\",o,arguments)},applyFilters:function(o){return gform.doHook(\"filter\",o,arguments)},removeAction:function(o,r){gform.removeHook(\"action\",o,r)},removeFilter:function(o,r,e){gform.removeHook(\"filter\",o,r,e)},addHook:function(o,r,e,t,n){null==gform.hooks[o][r]&&(gform.hooks[o][r]=[]);var d=gform.hooks[o][r];null==n&&(n=r+\"_\"+d.length),gform.hooks[o][r].push({tag:n,callable:e,priority:t=null==t?10:t})},doHook:function(r,o,e){var t;if(e=Array.prototype.slice.call(e,1),null!=gform.hooks[r][o]&&((o=gform.hooks[r][o]).sort(function(o,r){return o.priority-r.priority}),o.forEach(function(o){\"function\"!=typeof(t=o.callable)&&(t=window[t]),\"action\"==r?t.apply(null,e):e[0]=t.apply(null,e)})),\"filter\"==r)return e[0]},removeHook:function(o,r,t,n){var e;null!=gform.hooks[o][r]&&(e=(e=gform.hooks[o][r]).filter(function(o,r,e){return!!(null!=n&&n!=o.tag||null!=t&&t!=o.priority)}),gform.hooks[o][r]=e)}});\n\/* ]]> *\/\n<\/script>\n\n                <div class='gf_browser_gecko gform_wrapper gform_legacy_markup_wrapper gform-theme--no-framework' data-form-theme='legacy' data-form-index='0' id='gform_wrapper_4' style='display:none'>\n                        <div class='gform_heading'>\n                            <h3 class=\"gform_title\">Support Request<\/h3>\n                        <\/div><form method='post' enctype='multipart\/form-data'  id='gform_4'  action='\/es\/wp-json\/wp\/v2\/pages\/5858' data-formid='4' novalidate><div class='gf_invisible ginput_recaptchav3' data-sitekey='6LdAqbAqAAAAADyUWTwXIkPwn5Tgfn3t34nTtPkA' data-tabindex='0'><input id=\"input_1c9cb9763a57953039690a5d3630d98b\" class=\"gfield_recaptcha_response\" type=\"hidden\" name=\"input_1c9cb9763a57953039690a5d3630d98b\" value=\"\"\/><\/div>\n                        <div class='gform-body gform_body'><ul id='gform_fields_4' class='gform_fields top_label form_sublabel_below description_below validation_below'><li id=\"field_4_33\" class=\"gfield gfield--type-honeypot gform_validation_container field_sublabel_below gfield--has-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_4_33'>Comments<\/label><div class='ginput_container'><input name='input_33' id='input_4_33' type='text' value='' autocomplete='new-password'\/><\/div><div class='gfield_description' id='gfield_description_4_33'>This field is for validation purposes and should be left unchanged.<\/div><\/li><li id=\"field_4_26\" class=\"gfield gfield--type-checkbox gfield--type-choice gfield--input-type-checkbox gfield_contains_required field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label gfield_label_before_complex' >Which products do you need help with?<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_asterisk\">*<\/span><\/span><\/label><div class='ginput_container ginput_container_checkbox'><ul class='gfield_checkbox' id='input_4_26'><li class='gchoice gchoice_4_26_1'>\n\t\t\t\t\t\t\t\t<input class='gfield-choice-input' name='input_26.1' type='checkbox'  value='IntelliHub'  id='choice_4_26_1'   \/>\n\t\t\t\t\t\t\t\t<label for='choice_4_26_1' id='label_4_26_1' class='gform-field-label gform-field-label--type-inline'>IntelliHub<\/label>\n\t\t\t\t\t\t\t<\/li><li class='gchoice gchoice_4_26_2'>\n\t\t\t\t\t\t\t\t<input class='gfield-choice-input' name='input_26.2' type='checkbox'  value='Field Warrior'  id='choice_4_26_2'   \/>\n\t\t\t\t\t\t\t\t<label for='choice_4_26_2' id='label_4_26_2' class='gform-field-label gform-field-label--type-inline'>Field Warrior<\/label>\n\t\t\t\t\t\t\t<\/li><li class='gchoice gchoice_4_26_3'>\n\t\t\t\t\t\t\t\t<input class='gfield-choice-input' name='input_26.3' type='checkbox'  value='Monarch'  id='choice_4_26_3'   \/>\n\t\t\t\t\t\t\t\t<label for='choice_4_26_3' id='label_4_26_3' class='gform-field-label gform-field-label--type-inline'>Monarch<\/label>\n\t\t\t\t\t\t\t<\/li><li class='gchoice gchoice_4_26_4'>\n\t\t\t\t\t\t\t\t<input class='gfield-choice-input' name='input_26.4' type='checkbox'  value='FleetCam'  id='choice_4_26_4'   \/>\n\t\t\t\t\t\t\t\t<label for='choice_4_26_4' id='label_4_26_4' class='gform-field-label gform-field-label--type-inline'>FleetCam<\/label>\n\t\t\t\t\t\t\t<\/li><li class='gchoice gchoice_4_26_5'>\n\t\t\t\t\t\t\t\t<input class='gfield-choice-input' name='input_26.5' type='checkbox'  value='Route Matrix'  id='choice_4_26_5'   \/>\n\t\t\t\t\t\t\t\t<label for='choice_4_26_5' id='label_4_26_5' class='gform-field-label gform-field-label--type-inline'>Route Matrix<\/label>\n\t\t\t\t\t\t\t<\/li><li class='gchoice gchoice_4_26_6'>\n\t\t\t\t\t\t\t\t<input class='gfield-choice-input' name='input_26.6' type='checkbox'  value='Other'  id='choice_4_26_6'   \/>\n\t\t\t\t\t\t\t\t<label for='choice_4_26_6' id='label_4_26_6' class='gform-field-label gform-field-label--type-inline'>Other<\/label>\n\t\t\t\t\t\t\t<\/li><\/ul><\/div><\/li><li id=\"field_4_29\" class=\"gfield gfield--type-text gfield--input-type-text field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_4_29'>What version of Field Warrior are you using?<\/label><div class='ginput_container ginput_container_text'><input name='input_29' id='input_4_29' type='text' value='' class='medium'      aria-invalid=\"false\"   \/><\/div><\/li><li id=\"field_4_30\" class=\"gfield gfield--type-text gfield--input-type-text field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_4_30'>What version of Monarch are you using?<\/label><div class='ginput_container ginput_container_text'><input name='input_30' id='input_4_30' type='text' value='' class='medium'      aria-invalid=\"false\"   \/><\/div><\/li><li id=\"field_4_7\" class=\"gfield gfield--type-textarea gfield--input-type-textarea gfield_contains_required field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_4_7'>Please explain your issue, question, or request.<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_asterisk\">*<\/span><\/span><\/label><div class='ginput_container ginput_container_textarea'><textarea name='input_7' id='input_4_7' class='textarea medium'     aria-required=\"true\" aria-invalid=\"false\"   rows='10' cols='50'><\/textarea><\/div><\/li><li id=\"field_4_28\" class=\"gfield gfield--type-section gfield--input-type-section gsection field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><h2 class=\"gsection_title\">Vehicle &amp; Driver Information<\/h2><\/li><li id=\"field_4_22\" class=\"gfield gfield--type-name gfield--input-type-name field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label gfield_label_before_complex' >What is the driver&#039;s name?<\/label><div class='ginput_complex ginput_container ginput_container--name no_prefix has_first_name no_middle_name has_last_name no_suffix gf_name_has_2 ginput_container_name gform-grid-row' id='input_4_22'>\n                            \n                            <span id='input_4_22_3_container' class='name_first gform-grid-col gform-grid-col--size-auto' >\n                                                    <input type='text' name='input_22.3' id='input_4_22_3' value=''   aria-required='false'     \/>\n                                                    <label for='input_4_22_3' class='gform-field-label gform-field-label--type-sub '>First<\/label>\n                                                <\/span>\n                            \n                            <span id='input_4_22_6_container' class='name_last gform-grid-col gform-grid-col--size-auto' >\n                                                    <input type='text' name='input_22.6' id='input_4_22_6' value=''   aria-required='false'     \/>\n                                                    <label for='input_4_22_6' class='gform-field-label gform-field-label--type-sub '>Last<\/label>\n                                                <\/span>\n                            \n                        <\/div><\/li><li id=\"field_4_23\" class=\"gfield gfield--type-phone gfield--input-type-phone field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_4_23'>What is the driver&#039;s phone number?<\/label><div class='ginput_container ginput_container_phone'><input name='input_23' id='input_4_23' type='tel' value='' class='large'    aria-invalid=\"false\"   \/><\/div><\/li><li id=\"field_4_24\" class=\"gfield gfield--type-text gfield--input-type-text field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_4_24'>What is the vehicle&#039;s name in IntelliHub?<\/label><div class='ginput_container ginput_container_text'><input name='input_24' id='input_4_24' type='text' value='' class='large'      aria-invalid=\"false\"   \/><\/div><\/li><li id=\"field_4_21\" class=\"gfield gfield--type-checkbox gfield--type-choice gfield--input-type-checkbox field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label gfield_label_before_complex' >What type of device is the driver using?<\/label><div class='ginput_container ginput_container_checkbox'><ul class='gfield_checkbox' id='input_4_21'><li class='gchoice gchoice_4_21_1'>\n\t\t\t\t\t\t\t\t<input class='gfield-choice-input' name='input_21.1' type='checkbox'  value='Garmin'  id='choice_4_21_1'   \/>\n\t\t\t\t\t\t\t\t<label for='choice_4_21_1' id='label_4_21_1' class='gform-field-label gform-field-label--type-inline'>Garmin<\/label>\n\t\t\t\t\t\t\t<\/li><li class='gchoice gchoice_4_21_2'>\n\t\t\t\t\t\t\t\t<input class='gfield-choice-input' name='input_21.2' type='checkbox'  value='Tablet'  id='choice_4_21_2'   \/>\n\t\t\t\t\t\t\t\t<label for='choice_4_21_2' id='label_4_21_2' class='gform-field-label gform-field-label--type-inline'>Tablet<\/label>\n\t\t\t\t\t\t\t<\/li><li class='gchoice gchoice_4_21_3'>\n\t\t\t\t\t\t\t\t<input class='gfield-choice-input' name='input_21.3' type='checkbox'  value='Smartphone'  id='choice_4_21_3'   \/>\n\t\t\t\t\t\t\t\t<label for='choice_4_21_3' id='label_4_21_3' class='gform-field-label gform-field-label--type-inline'>Smartphone<\/label>\n\t\t\t\t\t\t\t<\/li><li class='gchoice gchoice_4_21_4'>\n\t\t\t\t\t\t\t\t<input class='gfield-choice-input' name='input_21.4' type='checkbox'  value='Not sure'  id='choice_4_21_4'   \/>\n\t\t\t\t\t\t\t\t<label for='choice_4_21_4' id='label_4_21_4' class='gform-field-label gform-field-label--type-inline'>Not sure<\/label>\n\t\t\t\t\t\t\t<\/li><\/ul><\/div><\/li><li id=\"field_4_27\" class=\"gfield gfield--type-section gfield--input-type-section gsection field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><h2 class=\"gsection_title\">Contact Information<\/h2><\/li><li id=\"field_4_5\" class=\"gfield gfield--type-text gfield--input-type-text gfield_contains_required field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_4_5'>Company Name<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_asterisk\">*<\/span><\/span><\/label><div class='ginput_container ginput_container_text'><input name='input_5' id='input_4_5' type='text' value='' class='large'     aria-required=\"true\" aria-invalid=\"false\"   \/><\/div><\/li><li id=\"field_4_32\" class=\"gfield gfield--type-name gfield--input-type-name gfield_contains_required field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label gfield_label_before_complex' >Your Name<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_asterisk\">*<\/span><\/span><\/label><div class='ginput_complex ginput_container ginput_container--name no_prefix has_first_name no_middle_name has_last_name no_suffix gf_name_has_2 ginput_container_name gform-grid-row' id='input_4_32'>\n                            \n                            <span id='input_4_32_3_container' class='name_first gform-grid-col gform-grid-col--size-auto' >\n                                                    <input type='text' name='input_32.3' id='input_4_32_3' value=''   aria-required='true'     \/>\n                                                    <label for='input_4_32_3' class='gform-field-label gform-field-label--type-sub '>First<\/label>\n                                                <\/span>\n                            \n                            <span id='input_4_32_6_container' class='name_last gform-grid-col gform-grid-col--size-auto' >\n                                                    <input type='text' name='input_32.6' id='input_4_32_6' value=''   aria-required='true'     \/>\n                                                    <label for='input_4_32_6' class='gform-field-label gform-field-label--type-sub '>Last<\/label>\n                                                <\/span>\n                            \n                        <\/div><\/li><li id=\"field_4_3\" class=\"gfield gfield--type-email gfield--input-type-email gfield_contains_required field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_4_3'>Your Email<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_asterisk\">*<\/span><\/span><\/label><div class='ginput_container ginput_container_email'>\n                            <input name='input_3' id='input_4_3' type='email' value='' class='large'    aria-required=\"true\" aria-invalid=\"false\"  \/>\n                        <\/div><\/li><li id=\"field_4_4\" class=\"gfield gfield--type-phone gfield--input-type-phone gfield_contains_required field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_4_4'>Your Phone Number<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_asterisk\">*<\/span><\/span><\/label><div class='ginput_container ginput_container_phone'><input name='input_4' id='input_4_4' type='tel' value='' class='large'   aria-required=\"true\" aria-invalid=\"false\"   \/><\/div><\/li><li id=\"field_4_9\" class=\"gfield gfield--type-hidden gfield--input-type-hidden gform_hidden field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><div class='ginput_container ginput_container_text'><input name='input_9' id='input_4_9' type='hidden' class='gform_hidden'  aria-invalid=\"false\" value='' \/><\/div><\/li><li id=\"field_4_10\" class=\"gfield gfield--type-hidden gfield--input-type-hidden gform_hidden field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><div class='ginput_container ginput_container_text'><input name='input_10' id='input_4_10' type='hidden' class='gform_hidden'  aria-invalid=\"false\" value='' \/><\/div><\/li><li id=\"field_4_11\" class=\"gfield gfield--type-hidden gfield--input-type-hidden gform_hidden field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><div class='ginput_container ginput_container_text'><input name='input_11' id='input_4_11' type='hidden' class='gform_hidden'  aria-invalid=\"false\" value='' \/><\/div><\/li><li id=\"field_4_12\" class=\"gfield gfield--type-hidden gfield--input-type-hidden gform_hidden field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><div class='ginput_container ginput_container_text'><input name='input_12' id='input_4_12' type='hidden' class='gform_hidden'  aria-invalid=\"false\" value='' \/><\/div><\/li><li id=\"field_4_13\" class=\"gfield gfield--type-hidden gfield--input-type-hidden gform_hidden field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><div class='ginput_container ginput_container_text'><input name='input_13' id='input_4_13' type='hidden' class='gform_hidden'  aria-invalid=\"false\" value='' \/><\/div><\/li><li id=\"field_4_14\" class=\"gfield gfield--type-hidden gfield--input-type-hidden gform_hidden field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><div class='ginput_container ginput_container_text'><input name='input_14' id='input_4_14' type='hidden' class='gform_hidden'  aria-invalid=\"false\" value='' \/><\/div><\/li><li id=\"field_4_15\" class=\"gfield gfield--type-hidden gfield--input-type-hidden gform_hidden field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><div class='ginput_container ginput_container_text'><input name='input_15' id='input_4_15' type='hidden' class='gform_hidden'  aria-invalid=\"false\" value='' \/><\/div><\/li><li id=\"field_4_16\" class=\"gfield gfield--type-hidden gfield--input-type-hidden gform_hidden field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><div class='ginput_container ginput_container_text'><input name='input_16' id='input_4_16' type='hidden' class='gform_hidden'  aria-invalid=\"false\" value='' \/><\/div><\/li><li id=\"field_4_17\" class=\"gfield gfield--type-hidden gfield--input-type-hidden gform_hidden field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><div class='ginput_container ginput_container_text'><input name='input_17' id='input_4_17' type='hidden' class='gform_hidden'  aria-invalid=\"false\" value='' \/><\/div><\/li><\/ul><\/div>\n        <div class='gform-footer gform_footer top_label'> <input type='submit' id='gform_submit_button_4' class='gform_button button' onclick='gform.submission.handleButtonClick(this);' data-submission-type='submit' value='Submit Request'  \/> \n            <input type='hidden' class='gform_hidden' name='gform_submission_method' data-js='gform_submission_method_4' value='postback' \/>\n            <input type='hidden' class='gform_hidden' name='gform_theme' data-js='gform_theme_4' id='gform_theme_4' value='legacy' \/>\n            <input type='hidden' class='gform_hidden' name='gform_style_settings' data-js='gform_style_settings_4' id='gform_style_settings_4' value='{&quot;inputPrimaryColor&quot;:&quot;#204ce5&quot;}' \/>\n            <input type='hidden' class='gform_hidden' name='is_submit_4' value='1' \/>\n            <input type='hidden' class='gform_hidden' name='gform_submit' value='4' \/>\n            \n            <input type='hidden' class='gform_hidden' name='gform_currency' data-currency='USD' value='JKMWj2NGaKKD1nHPoqpiRjXCaQGwMTGVJ8HK73p9cXWF8\/rR7t+xW9NHk44dl8hC4ybtkIL5I4o1zDfwqMB8gIN8g3vMOEvOLJsf96VyV+o+yYM=' \/>\n            <input type='hidden' class='gform_hidden' name='gform_unique_id' value='' \/>\n            <input type='hidden' class='gform_hidden' name='state_4' value='WyJbXSIsImUwNzU3YmFmNjY5NjZkN2I3NDdkNzg0Y2FkMDNkNTUzIl0=' \/>\n            <input type='hidden' autocomplete='off' class='gform_hidden' name='gform_target_page_number_4' id='gform_target_page_number_4' value='0' \/>\n            <input type='hidden' autocomplete='off' class='gform_hidden' name='gform_source_page_number_4' id='gform_source_page_number_4' value='1' \/>\n            <input type='hidden' name='gform_field_values' value='' \/>\n            \n        <\/div>\n                        <\/form>\n                        <\/div><script type=\"text\/javascript\">\n\/* <![CDATA[ *\/\n gform.initializeOnLoaded( function() {gformInitSpinner( 4, 'https:\/\/www.ftsgps.com\/wp-content\/plugins\/gravityforms\/images\/spinner.svg', true );jQuery('#gform_ajax_frame_4').on('load',function(){var contents = jQuery(this).contents().find('*').html();var is_postback = contents.indexOf('GF_AJAX_POSTBACK') >= 0;if(!is_postback){return;}var form_content = jQuery(this).contents().find('#gform_wrapper_4');var is_confirmation = jQuery(this).contents().find('#gform_confirmation_wrapper_4').length > 0;var is_redirect = contents.indexOf('gformRedirect(){') >= 0;var is_form = form_content.length > 0 && ! is_redirect && ! is_confirmation;var mt = parseInt(jQuery('html').css('margin-top'), 10) + parseInt(jQuery('body').css('margin-top'), 10) + 100;if(is_form){form_content.find('form').css('opacity', 0);jQuery('#gform_wrapper_4').html(form_content.html());if(form_content.hasClass('gform_validation_error')){jQuery('#gform_wrapper_4').addClass('gform_validation_error');} else {jQuery('#gform_wrapper_4').removeClass('gform_validation_error');}setTimeout( function() { \/* delay the scroll by 50 milliseconds to fix a bug in chrome *\/  }, 50 );if(window['gformInitDatepicker']) {gformInitDatepicker();}if(window['gformInitPriceFields']) {gformInitPriceFields();}var current_page = jQuery('#gform_source_page_number_4').val();gformInitSpinner( 4, 'https:\/\/www.ftsgps.com\/wp-content\/plugins\/gravityforms\/images\/spinner.svg', true );jQuery(document).trigger('gform_page_loaded', [4, current_page]);window['gf_submitting_4'] = false;}else if(!is_redirect){var confirmation_content = jQuery(this).contents().find('.GF_AJAX_POSTBACK').html();if(!confirmation_content){confirmation_content = contents;}jQuery('#gform_wrapper_4').replaceWith(confirmation_content);jQuery(document).trigger('gform_confirmation_loaded', [4]);window['gf_submitting_4'] = false;wp.a11y.speak(jQuery('#gform_confirmation_message_4').text());}else{jQuery('#gform_4').append(contents);if(window['gformRedirect']) {gformRedirect();}}jQuery(document).trigger(\"gform_pre_post_render\", [{ formId: \"4\", currentPage: \"current_page\", abort: function() { this.preventDefault(); } }]);        if (event && event.defaultPrevented) {                return;        }        const gformWrapperDiv = document.getElementById( \"gform_wrapper_4\" );        if ( gformWrapperDiv ) {            const visibilitySpan = document.createElement( \"span\" );            visibilitySpan.id = \"gform_visibility_test_4\";            gformWrapperDiv.insertAdjacentElement( \"afterend\", visibilitySpan );        }        const visibilityTestDiv = document.getElementById( \"gform_visibility_test_4\" );        let postRenderFired = false;        function triggerPostRender() {            if ( postRenderFired ) {                return;            }            postRenderFired = true;            gform.core.triggerPostRenderEvents( 4, current_page );            if ( visibilityTestDiv ) {                visibilityTestDiv.parentNode.removeChild( visibilityTestDiv );            }        }        function debounce( func, wait, immediate ) {            var timeout;            return function() {                var context = this, args = arguments;                var later = function() {                    timeout = null;                    if ( !immediate ) func.apply( context, args );                };                var callNow = immediate && !timeout;                clearTimeout( timeout );                timeout = setTimeout( later, wait );                if ( callNow ) func.apply( context, args );            };        }        const debouncedTriggerPostRender = debounce( function() {            triggerPostRender();        }, 200 );        if ( visibilityTestDiv && visibilityTestDiv.offsetParent === null ) {            const observer = new MutationObserver( ( mutations ) => {                mutations.forEach( ( mutation ) => {                    if ( mutation.type === 'attributes' && visibilityTestDiv.offsetParent !== null ) {                        debouncedTriggerPostRender();                        observer.disconnect();                    }                });            });            observer.observe( document.body, {                attributes: true,                childList: false,                subtree: true,                attributeFilter: [ 'style', 'class' ],            });        } else {            triggerPostRender();        }    } );} ); \n\/* ]]> *\/\n<\/script>\n","protected":false},"excerpt":{"rendered":"<p>Solicitud de apoyo<\/p>","protected":false},"author":3,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"content-type":"","footnotes":""},"class_list":["post-5858","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Customer Support<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ftsgps.com\/es\/atencion-al-cliente\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Customer Support\" \/>\n<meta property=\"og:description\" content=\"Support Request\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ftsgps.com\/es\/atencion-al-cliente\/\" \/>\n<meta property=\"og:site_name\" content=\"Forward Thinking Systems\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ftsGPS\/\" \/>\n<meta property=\"article:modified_time\" content=\"2023-09-20T14:02:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ftsgps.com\/wp-content\/uploads\/2026\/02\/ForwardThinkingSystems.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@FTSGPS\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Atenci\u00f3n al cliente","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ftsgps.com\/es\/atencion-al-cliente\/","og_locale":"es_MX","og_type":"article","og_title":"Customer Support","og_description":"Support Request","og_url":"https:\/\/www.ftsgps.com\/es\/atencion-al-cliente\/","og_site_name":"Forward Thinking Systems","article_publisher":"https:\/\/www.facebook.com\/ftsGPS\/","article_modified_time":"2023-09-20T14:02:58+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/www.ftsgps.com\/wp-content\/uploads\/2026\/02\/ForwardThinkingSystems.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@FTSGPS","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.ftsgps.com\/customer-support\/","url":"https:\/\/www.ftsgps.com\/customer-support\/","name":"Atenci\u00f3n al cliente","isPartOf":{"@id":"https:\/\/www.ftsgps.com\/#website"},"datePublished":"2022-10-17T09:45:43+00:00","dateModified":"2023-09-20T14:02:58+00:00","inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ftsgps.com\/customer-support\/"]}]},{"@type":"WebSite","@id":"https:\/\/www.ftsgps.com\/#website","url":"https:\/\/www.ftsgps.com\/","name":"Sistemas de previsi\u00f3n","description":"Adel\u00e1ntate a los dem\u00e1s","publisher":{"@id":"https:\/\/www.ftsgps.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ftsgps.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.ftsgps.com\/#organization","name":"Sistemas de previsi\u00f3n","alternateName":"FTSGPS","url":"https:\/\/www.ftsgps.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.ftsgps.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.ftsgps.com\/wp-content\/uploads\/2019\/07\/Forward-Thinking-Systems-logo.svg","contentUrl":"https:\/\/www.ftsgps.com\/wp-content\/uploads\/2019\/07\/Forward-Thinking-Systems-logo.svg","width":656,"height":129,"caption":"Forward Thinking Systems"},"image":{"@id":"https:\/\/www.ftsgps.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ftsGPS\/","https:\/\/x.com\/FTSGPS","https:\/\/www.linkedin.com\/company\/forward-thinking-systems"]}]}},"_links":{"self":[{"href":"https:\/\/www.ftsgps.com\/es\/wp-json\/wp\/v2\/pages\/5858","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ftsgps.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.ftsgps.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.ftsgps.com\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ftsgps.com\/es\/wp-json\/wp\/v2\/comments?post=5858"}],"version-history":[{"count":6,"href":"https:\/\/www.ftsgps.com\/es\/wp-json\/wp\/v2\/pages\/5858\/revisions"}],"predecessor-version":[{"id":7910,"href":"https:\/\/www.ftsgps.com\/es\/wp-json\/wp\/v2\/pages\/5858\/revisions\/7910"}],"wp:attachment":[{"href":"https:\/\/www.ftsgps.com\/es\/wp-json\/wp\/v2\/media?parent=5858"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}